{"id":2967,"date":"2021-07-21T11:41:57","date_gmt":"2021-07-21T11:41:57","guid":{"rendered":"https:\/\/creamycreation.com\/2021\/07\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/"},"modified":"2021-07-23T10:03:25","modified_gmt":"2021-07-23T10:03:25","slug":"nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio","status":"publish","type":"post","link":"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/","title":{"rendered":"Nuestra innovaci\u00f3n vegana est\u00e1 en el Top 10 de lanzamientos de junio"},"content":{"rendered":"<h2>Nuestra Pr\u00f3xima Generaci\u00f3n Vegana ha entrado en el Top 10 de lanzamientos de junio de Spirits Business<\/h2>\n<h3>\u00bfQu\u00e9 lo hace tan especial? Esta l\u00ednea vegana de nueva generaci\u00f3n es tan indulgente y suave como un licor de crema tradicional<\/h3>\n<p>Adem\u00e1s, est\u00e1 disponible en una l\u00ednea sin soja para los propietarios de marcas que buscan opciones de etiqueta limpia, o una l\u00ednea mezclable, para los propietarios de marcas que buscan lanzar una bebida cremosa vegana de moda que los consumidores y los mezcladores pueden mezclar con zumo, caf\u00e9 e incluso t\u00f3nica.<\/p>\n<p>Vis\u00edtenos en <a href=\"https:\/\/www.thespiritsbusiness.com\/2021\/07\/top-10-spirits-launches-in-june-2021\/5\/\">www.thespiritbusiness.com<\/a> y conozca nuestras <a href=\"https:\/\/creamycreation.com\/es\/productos\/alternativas-no-lacteas-y-veganas\/\">alternativas de crema no l\u00e1ctea y vegana.<\/a><\/p>\n<p>&nbsp;<\/p>\n<h4>\u00bfBUSCA UN SOCIO PARA LA FORMULACI\u00d3N DE BEBIDAS?<\/h4>\n<p>Le ayudaremos a desarrollar y producir su bebida emulsionada perfecta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2890 size-full\" src=\"https:\/\/creamycreation.com\/wp-content\/uploads\/2021\/06\/VEGAN-TEASER_BOTTLES_CC.png\" alt=\"\" width=\"2000\" height=\"1408\" srcset=\"https:\/\/creamycreation.com\/wp-content\/uploads\/2021\/06\/VEGAN-TEASER_BOTTLES_CC.png 2000w, https:\/\/creamycreation.com\/wp-content\/uploads\/2021\/06\/VEGAN-TEASER_BOTTLES_CC-300x211.png 300w, https:\/\/creamycreation.com\/wp-content\/uploads\/2021\/06\/VEGAN-TEASER_BOTTLES_CC-1024x721.png 1024w, https:\/\/creamycreation.com\/wp-content\/uploads\/2021\/06\/VEGAN-TEASER_BOTTLES_CC-768x541.png 768w, https:\/\/creamycreation.com\/wp-content\/uploads\/2021\/06\/VEGAN-TEASER_BOTTLES_CC-1536x1081.png 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra Pr\u00f3xima Generaci\u00f3n Vegana ha entrado en el Top 10 de lanzamientos de junio de Spirits Business \u00bfQu\u00e9 lo hace&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2932,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[38],"tags":[],"class_list":["post-2967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuestra innovaci\u00f3n vegana est\u00e1 en el Top 10 de lanzamientos de junio - Creamy Creation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuestra innovaci\u00f3n vegana est\u00e1 en el Top 10 de lanzamientos de junio - Creamy Creation\" \/>\n<meta property=\"og:description\" content=\"Nuestra Pr\u00f3xima Generaci\u00f3n Vegana ha entrado en el Top 10 de lanzamientos de junio de Spirits Business \u00bfQu\u00e9 lo hace...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/\" \/>\n<meta property=\"og:site_name\" content=\"Creamy Creation\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CreamyCreationPage\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-21T11:41:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-23T10:03:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/creamycreation.com\/wp-content\/uploads\/2020\/09\/Vegan-Creamy-Liqueur_Mixable-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"564\" \/>\n\t<meta property=\"og:image:height\" content=\"843\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Georgia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Georgia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\\\/\"},\"author\":{\"name\":\"Georgia\",\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/#\\\/schema\\\/person\\\/547f3d8109038ece26190ceb21a843a3\"},\"headline\":\"Nuestra innovaci\u00f3n vegana est\u00e1 en el Top 10 de lanzamientos de junio\",\"datePublished\":\"2021-07-21T11:41:57+00:00\",\"dateModified\":\"2021-07-23T10:03:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\\\/\"},\"wordCount\":146,\"publisher\":{\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/creamycreation.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Vegan-Creamy-Liqueur_Mixable-1.png\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\\\/\",\"url\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\\\/\",\"name\":\"Nuestra innovaci\u00f3n vegana est\u00e1 en el Top 10 de lanzamientos de junio - Creamy Creation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/creamycreation.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Vegan-Creamy-Liqueur_Mixable-1.png\",\"datePublished\":\"2021-07-21T11:41:57+00:00\",\"dateModified\":\"2021-07-23T10:03:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/creamycreation.com\\\/es\\\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/creamycreation.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Vegan-Creamy-Liqueur_Mixable-1.png\",\"contentUrl\":\"https:\\\/\\\/creamycreation.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Vegan-Creamy-Liqueur_Mixable-1.png\",\"width\":564,\"height\":843,\"caption\":\"A bottle of pink vegan cream liqueur being poured into a highball glass with ice\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestra innovaci\u00f3n vegana est\u00e1 en el Top 10 de lanzamientos de junio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/\",\"name\":\"Creamy Creation\",\"description\":\"Emulsified Beverage Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/#organization\",\"name\":\"Creamy Creation\",\"url\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/creamycreation.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Creamy_Creation_Favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/creamycreation.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Creamy_Creation_Favicon.jpg\",\"width\":686,\"height\":686,\"caption\":\"Creamy Creation\"},\"image\":{\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CreamyCreationPage\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/creamycreation.com\\\/es\\\/#\\\/schema\\\/person\\\/547f3d8109038ece26190ceb21a843a3\",\"name\":\"Georgia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73e549bcff81a175973f8f6eeefc4c24c62f1344c315250ec77472e97f175242?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73e549bcff81a175973f8f6eeefc4c24c62f1344c315250ec77472e97f175242?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73e549bcff81a175973f8f6eeefc4c24c62f1344c315250ec77472e97f175242?s=96&d=mm&r=g\",\"caption\":\"Georgia\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuestra innovaci\u00f3n vegana est\u00e1 en el Top 10 de lanzamientos de junio - Creamy Creation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/","og_locale":"es_ES","og_type":"article","og_title":"Nuestra innovaci\u00f3n vegana est\u00e1 en el Top 10 de lanzamientos de junio - Creamy Creation","og_description":"Nuestra Pr\u00f3xima Generaci\u00f3n Vegana ha entrado en el Top 10 de lanzamientos de junio de Spirits Business \u00bfQu\u00e9 lo hace...","og_url":"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/","og_site_name":"Creamy Creation","article_publisher":"https:\/\/www.facebook.com\/CreamyCreationPage","article_published_time":"2021-07-21T11:41:57+00:00","article_modified_time":"2021-07-23T10:03:25+00:00","og_image":[{"width":564,"height":843,"url":"https:\/\/creamycreation.com\/wp-content\/uploads\/2020\/09\/Vegan-Creamy-Liqueur_Mixable-1.png","type":"image\/png"}],"author":"Georgia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Georgia","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/#article","isPartOf":{"@id":"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/"},"author":{"name":"Georgia","@id":"https:\/\/creamycreation.com\/es\/#\/schema\/person\/547f3d8109038ece26190ceb21a843a3"},"headline":"Nuestra innovaci\u00f3n vegana est\u00e1 en el Top 10 de lanzamientos de junio","datePublished":"2021-07-21T11:41:57+00:00","dateModified":"2021-07-23T10:03:25+00:00","mainEntityOfPage":{"@id":"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/"},"wordCount":146,"publisher":{"@id":"https:\/\/creamycreation.com\/es\/#organization"},"image":{"@id":"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/#primaryimage"},"thumbnailUrl":"https:\/\/creamycreation.com\/wp-content\/uploads\/2020\/09\/Vegan-Creamy-Liqueur_Mixable-1.png","articleSection":["Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/","url":"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/","name":"Nuestra innovaci\u00f3n vegana est\u00e1 en el Top 10 de lanzamientos de junio - Creamy Creation","isPartOf":{"@id":"https:\/\/creamycreation.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/#primaryimage"},"image":{"@id":"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/#primaryimage"},"thumbnailUrl":"https:\/\/creamycreation.com\/wp-content\/uploads\/2020\/09\/Vegan-Creamy-Liqueur_Mixable-1.png","datePublished":"2021-07-21T11:41:57+00:00","dateModified":"2021-07-23T10:03:25+00:00","breadcrumb":{"@id":"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/#primaryimage","url":"https:\/\/creamycreation.com\/wp-content\/uploads\/2020\/09\/Vegan-Creamy-Liqueur_Mixable-1.png","contentUrl":"https:\/\/creamycreation.com\/wp-content\/uploads\/2020\/09\/Vegan-Creamy-Liqueur_Mixable-1.png","width":564,"height":843,"caption":"A bottle of pink vegan cream liqueur being poured into a highball glass with ice"},{"@type":"BreadcrumbList","@id":"https:\/\/creamycreation.com\/es\/nuestra-innovacion-vegana-esta-en-el-top-10-de-lanzamientos-de-junio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/creamycreation.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Nuestra innovaci\u00f3n vegana est\u00e1 en el Top 10 de lanzamientos de junio"}]},{"@type":"WebSite","@id":"https:\/\/creamycreation.com\/es\/#website","url":"https:\/\/creamycreation.com\/es\/","name":"Creamy Creation","description":"Emulsified Beverage Solutions","publisher":{"@id":"https:\/\/creamycreation.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/creamycreation.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/creamycreation.com\/es\/#organization","name":"Creamy Creation","url":"https:\/\/creamycreation.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/creamycreation.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/creamycreation.com\/wp-content\/uploads\/2020\/09\/Creamy_Creation_Favicon.jpg","contentUrl":"https:\/\/creamycreation.com\/wp-content\/uploads\/2020\/09\/Creamy_Creation_Favicon.jpg","width":686,"height":686,"caption":"Creamy Creation"},"image":{"@id":"https:\/\/creamycreation.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CreamyCreationPage"]},{"@type":"Person","@id":"https:\/\/creamycreation.com\/es\/#\/schema\/person\/547f3d8109038ece26190ceb21a843a3","name":"Georgia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/73e549bcff81a175973f8f6eeefc4c24c62f1344c315250ec77472e97f175242?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/73e549bcff81a175973f8f6eeefc4c24c62f1344c315250ec77472e97f175242?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/73e549bcff81a175973f8f6eeefc4c24c62f1344c315250ec77472e97f175242?s=96&d=mm&r=g","caption":"Georgia"}}]}},"_links":{"self":[{"href":"https:\/\/creamycreation.com\/es\/wp-json\/wp\/v2\/posts\/2967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/creamycreation.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/creamycreation.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/creamycreation.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/creamycreation.com\/es\/wp-json\/wp\/v2\/comments?post=2967"}],"version-history":[{"count":0,"href":"https:\/\/creamycreation.com\/es\/wp-json\/wp\/v2\/posts\/2967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/creamycreation.com\/es\/wp-json\/wp\/v2\/media\/2932"}],"wp:attachment":[{"href":"https:\/\/creamycreation.com\/es\/wp-json\/wp\/v2\/media?parent=2967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/creamycreation.com\/es\/wp-json\/wp\/v2\/categories?post=2967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/creamycreation.com\/es\/wp-json\/wp\/v2\/tags?post=2967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}